{"id":2506,"date":"2024-03-11T14:01:56","date_gmt":"2024-03-11T17:01:56","guid":{"rendered":"https:\/\/platinumagencias.com\/?page_id=2506"},"modified":"2024-03-12T11:50:50","modified_gmt":"2024-03-12T14:50:50","slug":"criacao-de-identidade-visual-de-marca","status":"publish","type":"page","link":"https:\/\/platinumagencias.com\/ja\/criacao-de-identidade-visual-de-marca\/","title":{"rendered":"\u306e\u5275\u9020\u3092\u30d3\u30b8\u30e5\u30a2\u30eb-\u30a2\u30a4\u30c7\u30f3\u30c6\u30a3\u30c6\u30a3\u306e\u30d6\u30e9\u30f3\u30c9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2506\" class=\"elementor elementor-2506\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e86fa30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e86fa30\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9cda33\" data-id=\"b9cda33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58d0d41 elementor-widget elementor-widget-heading\" data-id=\"58d0d41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\n\nCria\u00e7\u00e3o de Identidade Visual da Marca<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-491e9b5 elementor-widget elementor-widget-text-editor\" data-id=\"491e9b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Conhe\u00e7a um pouco mais dos nosso pacote de cria\u00e7\u00e3o de identidade visual de marca!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c540576 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c540576\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-929c567\" data-id=\"929c567\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-813d8c4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"813d8c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b350094 elementor-widget elementor-widget-heading\" data-id=\"b350094\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\n\nCria\u00e7\u00e3o de Identidade Visual da Marca<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b04bbf5 elementor-widget elementor-widget-text-editor\" data-id=\"b04bbf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nos encarregamos de criar toda a identidade visual da sua marca. Voc\u00ea sabia que uma apresenta\u00e7\u00e3o bem elaborada aumenta em 50% as chances de fechar um neg\u00f3cio? Conte com a Platinum para garantir o sucesso da sua marca.<\/p><p>No pacote de cria\u00e7\u00e3o de identidade visual da marca est\u00e1 incluso:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4f4a67 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b4f4a67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cria\u00e7\u00e3o de logotipo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Identidade visual: Cores e Fontes para a marca<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Posicionamento nas redes sociais<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Apresenta\u00e7\u00e3o em power point<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87ce6d9 elementor-widget elementor-widget-button\" data-id=\"87ce6d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wa.me\/5511994952660?text=Ol%C3%A1%20tudo%20bem%3F%20Gostaria%20de%20fazer%20um%20or%C3%A7amento%20com%20voc%C3%AAs%20da%20Platinum!\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cotratar agora<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-958edd3\" data-id=\"958edd3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c05e40e elementor-widget elementor-widget-image\" data-id=\"c05e40e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/Criacao-de-identidade-visual-1024x1024.webp\" class=\"attachment-large size-large wp-image-2509\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/Criacao-de-identidade-visual-1024x1024.webp 1024w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/Criacao-de-identidade-visual-300x300.webp 300w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/Criacao-de-identidade-visual-150x150.webp 150w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/Criacao-de-identidade-visual-768x768.webp 768w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/Criacao-de-identidade-visual-jpg.webp 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-253abe7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"253abe7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df82c77\" data-id=\"df82c77\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ccb724a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ccb724a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-489b415\" data-id=\"489b415\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d66f6a8 elementor-widget elementor-widget-image\" data-id=\"d66f6a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1080\" height=\"1920\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-1-jpg.webp\" class=\"attachment-full size-full wp-image-2511\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-1-jpg.webp 1080w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-1-169x300.webp 169w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-1-576x1024.webp 576w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-1-768x1365.webp 768w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-1-864x1536.webp 864w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-66a04cc\" data-id=\"66a04cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34ac146 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"34ac146\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fa5d9b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"1fa5d9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Cria\u00e7\u00e3o de logotipo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59d8273 elementor-widget elementor-widget-text-editor\" data-id=\"59d8273\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Destaque-se da concorr\u00eancia com um logotipo \u00fanico e memor\u00e1vel, criado sob medida para a sua marca com o nosso servi\u00e7o de Cria\u00e7\u00e3o de Logotipo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1d64e73\" data-id=\"1d64e73\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-423856e elementor-widget elementor-widget-text-editor\" data-id=\"423856e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A Cria\u00e7\u00e3o de Logotipo oferece uma abordagem personalizada e inovadora para desenvolver uma identidade visual distintiva para sua marca. Trabalhando de perto com nossos designers, garantimos que o logotipo captura a ess\u00eancia da sua empresa e ressoa com seu p\u00fablico-alvo. Utilizando t\u00e9cnicas de design de ponta, criamos um logotipo que n\u00e3o apenas se destaca da concorr\u00eancia, mas tamb\u00e9m fortalece a identidade da sua marca, deixando uma impress\u00e3o memor\u00e1vel nos clientes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9e531aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e531aa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d11ed70\" data-id=\"d11ed70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dc4a4c elementor-widget elementor-widget-image\" data-id=\"2dc4a4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1080\" height=\"1920\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-2-jpg.webp\" class=\"attachment-full size-full wp-image-2512\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-2-jpg.webp 1080w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-2-169x300.webp 169w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-2-576x1024.webp 576w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-2-768x1365.webp 768w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-2-864x1536.webp 864w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-33971b9\" data-id=\"33971b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28b6546 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"28b6546\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-423120b elementor-widget elementor-widget-heading\" data-id=\"423120b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Identidade visual: Cores e Fontes para a marca<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b77406 elementor-widget elementor-widget-text-editor\" data-id=\"5b77406\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Destaque sua marca com uma identidade visual \u00fanica e memor\u00e1vel, criada sob medida com nosso servi\u00e7o de Identidade Visual: Cores e Fontes para a Marca<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-32647e5\" data-id=\"32647e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d833a8 elementor-widget elementor-widget-text-editor\" data-id=\"2d833a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A Identidade Visual: oferece uma abordagem personalizada para definir as cores e fontes que representar\u00e3o sua marca de forma consistente e impactante. Trabalhamos em estreita colabora\u00e7\u00e3o com voc\u00ea para entender a ess\u00eancia da sua marca, seus valores e p\u00fablico-alvo. Utilizando princ\u00edpios de design e psicologia das cores, selecionamos paletas de cores e fontes que n\u00e3o apenas refletem a personalidade da sua marca, mas tamb\u00e9m criam uma conex\u00e3o emocional com seu p\u00fablico-alvo. O resultado \u00e9 uma identidade visual coesa e profissional que diferencia sua marca e fortalece sua presen\u00e7a online e offline.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5e3c304 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e3c304\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3656439\" data-id=\"3656439\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-630ad01 elementor-widget elementor-widget-image\" data-id=\"630ad01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1920\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-3-jpg.webp\" class=\"attachment-full size-full wp-image-2513\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-3-jpg.webp 1080w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-3-169x300.webp 169w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-3-576x1024.webp 576w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-3-768x1365.webp 768w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-3-864x1536.webp 864w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f03f634\" data-id=\"f03f634\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-449be5a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"449be5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f505cc8 elementor-widget elementor-widget-heading\" data-id=\"f505cc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Posicionamento nas redes sociais<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e27570a elementor-widget elementor-widget-text-editor\" data-id=\"e27570a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Impulsionamos o engajamento, reconhecimento e fideliza\u00e7\u00e3o da sua marca com nossa estrat\u00e9gia personalizada de posicionamento nas redes sociais.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-eb6161f\" data-id=\"eb6161f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9705d53 elementor-widget elementor-widget-text-editor\" data-id=\"9705d53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"flex-1 overflow-hidden\"><div class=\"react-scroll-to-bottom--css-wttxm-79elbk h-full\"><div class=\"react-scroll-to-bottom--css-wttxm-1n7m0yu\"><div class=\"flex flex-col text-sm pb-9\"><div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-71\"><div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\"><div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group final-completion\"><div class=\"relative flex w-full flex-col agent-turn\"><div class=\"flex-col gap-1 md:gap-3\"><div class=\"flex flex-grow flex-col max-w-full\"><div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" data-message-author-role=\"assistant\" data-message-id=\"68cd21ca-be0e-4664-98d9-8f0696da6391\"><div class=\"markdown prose w-full break-words dark:prose-invert light\"><p>O Posicionamento nas Redes Sociais cria uma estrat\u00e9gia personalizada para sua marca, focando em conte\u00fado relevante, engajamento e constru\u00e7\u00e3o de relacionamentos. Monitoramos tend\u00eancias e utilizamos t\u00e9cnicas de gerenciamento de comunidades para garantir que sua presen\u00e7a se destaque e permane\u00e7a relevante. O objetivo \u00e9 fortalecer a percep\u00e7\u00e3o da marca, aumentar o alcance e impulsionar o envolvimento do p\u00fablico, resultando em maior reconhecimento e fideliza\u00e7\u00e3o dos clientes.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-42fa4ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42fa4ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a7a4736\" data-id=\"a7a4736\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7152a72 elementor-widget elementor-widget-image\" data-id=\"7152a72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1920\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-jpg.webp\" class=\"attachment-full size-full wp-image-2510\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-jpg.webp 1080w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-169x300.webp 169w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-576x1024.webp 576w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-768x1365.webp 768w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/identidade-visual-864x1536.webp 864w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f04aa24\" data-id=\"f04aa24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-516795a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"516795a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a62431 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"2a62431\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Apresenta\u00e7\u00e3o em power point<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12d858d elementor-widget elementor-widget-text-editor\" data-id=\"12d858d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Crie apresenta\u00e7\u00f5es impressionantes que cativam e influenciam com nosso servi\u00e7o profissional de PowerPoint para empresas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-23f53c3\" data-id=\"23f53c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80e74d6 elementor-widget elementor-widget-text-editor\" data-id=\"80e74d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A cria\u00e7\u00e3o de apresenta\u00e7\u00f5es em PowerPoint oferece solu\u00e7\u00f5es personalizadas e profissionais para atender \u00e0s necessidades espec\u00edficas de comunica\u00e7\u00e3o visual das empresas dos nossos clientes. Utilizando design criativo e conte\u00fado relevante, desenvolvemos apresenta\u00e7\u00f5es impactantes que cativam o p\u00fablico-alvo e transmitem a mensagem de forma clara e eficaz. Nosso objetivo \u00e9 criar apresenta\u00e7\u00f5es que impressionem e influenciem, ajudando nossos clientes a alcan\u00e7arem seus objetivos de comunica\u00e7\u00e3o e neg\u00f3cios.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea82759 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea82759\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-718f7de\" data-id=\"718f7de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-629925f elementor-widget elementor-widget-heading\" data-id=\"629925f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Entre em contato conosco<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d633fce elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d633fce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5577648 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"5577648\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"2506\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"5577648\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Cria\u00e7\u00e3o de Identidade Visual de Marca \u2013 Ag\u00eancia Platinum\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"2506\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-number elementor-field-group elementor-column elementor-field-group-field_6773b09 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_6773b09\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTelefone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t<input type=\"number\" name=\"form_fields[field_6773b09]\" id=\"form-field-field_6773b09\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Telefone\" min=\"\" max=\"\" >\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMensagem\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Mensagem\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de33711 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"de33711\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d57d479 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d57d479\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cria\u00e7\u00e3o de Identidade Visual da Marca Conhe\u00e7a um pouco mais dos nosso pacote de cria\u00e7\u00e3o de identidade visual de marca! Cria\u00e7\u00e3o de Identidade Visual da Marca Nos encarregamos de criar toda a identidade visual da sua marca. Voc\u00ea sabia que uma apresenta\u00e7\u00e3o bem elaborada aumenta em 50% as chances de fechar um neg\u00f3cio? Conte com a Platinum para garantir o sucesso da sua marca. No pacote de cria\u00e7\u00e3o de identidade visual da marca est\u00e1 incluso: Cria\u00e7\u00e3o de logotipo Identidade visual: Cores e Fontes para a marca Posicionamento nas redes sociais Apresenta\u00e7\u00e3o em power point Cotratar agora Cria\u00e7\u00e3o de logotipo Destaque-se da concorr\u00eancia com um logotipo \u00fanico e memor\u00e1vel, criado sob [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2506","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Cria\u00e7\u00e3o de Identidade Visual da Marca Conhe\u00e7a um pouco mais dos nosso pacote de cria\u00e7\u00e3o de identidade visual de marca! Cria\u00e7\u00e3o de Identidade Visual da Marca Nos encarregamos de criar toda a identidade visual da sua marca. Voc\u00ea sabia que uma apresenta\u00e7\u00e3o bem elaborada aumenta em 50% as chances de fechar um neg\u00f3cio? Conte com\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/platinumagencias.com\/ja\/criacao-de-identidade-visual-de-marca\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"ja_JP\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ag\u00eancia Platinum \u2013 Ag\u00eancia de Marketing Digital\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Cria\u00e7\u00e3o de Identidade Visual de Marca \u2013 Ag\u00eancia Platinum\" \/>\n\t\t<meta property=\"og:description\" content=\"Cria\u00e7\u00e3o de Identidade Visual da Marca Conhe\u00e7a um pouco mais dos nosso pacote de cria\u00e7\u00e3o de identidade visual de marca! Cria\u00e7\u00e3o de Identidade Visual da Marca Nos encarregamos de criar toda a identidade visual da sua marca. Voc\u00ea sabia que uma apresenta\u00e7\u00e3o bem elaborada aumenta em 50% as chances de fechar um neg\u00f3cio? Conte com\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/platinumagencias.com\/ja\/criacao-de-identidade-visual-de-marca\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/cropped-Design-sem-nome-2022-10-11T100526.548.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/cropped-Design-sem-nome-2022-10-11T100526.548.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-03-11T17:01:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-03-12T14:50:50+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Cria\u00e7\u00e3o de Identidade Visual de Marca \u2013 Ag\u00eancia Platinum\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Cria\u00e7\u00e3o de Identidade Visual da Marca Conhe\u00e7a um pouco mais dos nosso pacote de cria\u00e7\u00e3o de identidade visual de marca! Cria\u00e7\u00e3o de Identidade Visual da Marca Nos encarregamos de criar toda a identidade visual da sua marca. Voc\u00ea sabia que uma apresenta\u00e7\u00e3o bem elaborada aumenta em 50% as chances de fechar um neg\u00f3cio? Conte com\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/cropped-Design-sem-nome-2022-10-11T100526.548.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/ja\\\/criacao-de-identidade-visual-de-marca\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/ja#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/platinumagencias.com\\\/ja\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/ja\\\/criacao-de-identidade-visual-de-marca\\\/#listItem\",\"name\":\"Cria\\u00e7\\u00e3o de Identidade Visual de Marca\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/ja\\\/criacao-de-identidade-visual-de-marca\\\/#listItem\",\"position\":2,\"name\":\"Cria\\u00e7\\u00e3o de Identidade Visual de Marca\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/ja#listItem\",\"name\":\"In\\u00edcio\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/ja\\\/#organization\",\"name\":\"Ag\\u00eancia Platinum\",\"description\":\"Ag\\u00eancia de Marketing Digital\",\"url\":\"https:\\\/\\\/platinumagencias.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/platinumagencias.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-Agencia-Platinum.png\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/ja\\\/criacao-de-identidade-visual-de-marca\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/ja\\\/criacao-de-identidade-visual-de-marca\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/ja\\\/criacao-de-identidade-visual-de-marca\\\/#webpage\",\"url\":\"https:\\\/\\\/platinumagencias.com\\\/ja\\\/criacao-de-identidade-visual-de-marca\\\/\",\"name\":\"Cria\\u00e7\\u00e3o de Identidade Visual de Marca \\u2013 Ag\\u00eancia Platinum\",\"description\":\"Cria\\u00e7\\u00e3o de Identidade Visual da Marca Conhe\\u00e7a um pouco mais dos nosso pacote de cria\\u00e7\\u00e3o de identidade visual de marca! Cria\\u00e7\\u00e3o de Identidade Visual da Marca Nos encarregamos de criar toda a identidade visual da sua marca. Voc\\u00ea sabia que uma apresenta\\u00e7\\u00e3o bem elaborada aumenta em 50% as chances de fechar um neg\\u00f3cio? Conte com\",\"inLanguage\":\"ja\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/ja\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/ja\\\/criacao-de-identidade-visual-de-marca\\\/#breadcrumblist\"},\"datePublished\":\"2024-03-11T14:01:56-03:00\",\"dateModified\":\"2024-03-12T11:50:50-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/platinumagencias.com\\\/ja\\\/\",\"name\":\"Ag\\u00eancia Platinum\",\"description\":\"Ag\\u00eancia de Marketing Digital\",\"inLanguage\":\"ja\",\"publisher\":{\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/ja\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u4f5c\u6210\u306e\u30f4\u30a3\u30b8\u30e5\u30a2\u30eb\u30a2\u30a4\u30c7\u30f3\u30c6\u30a3\u30c6\u30a3\u306e\u30d6\u30e9\u30f3\u30c9\u3001\u30d7\u30e9\u30c1\u30ca","description":"\u4f5c\u6210\u306e\u30f4\u30a3\u30b8\u30e5\u30a2\u30eb\u30a2\u30a4\u30c7\u30f3\u30c6\u30a3\u30c6\u30a3\u306e\u30d6\u30e9\u30f3\u30c9\u306b\u77e5\u308a\u5408\u3063\u3066\u3044\u304d\u307e\u3057\u3087\u3046\u30a8\u30af\u30b9\u30da\u30c7\u30a3\u30a2\u306e\u30ad\u30e3\u30f3\u30bb\u30eb\u306e\u5275\u9020\u3092\u30d3\u30b8\u30e5\u30a2\u30eb-\u30a2\u30a4\u30c7\u30f3\u30c6\u30a3\u30c6\u30a3\u306e\u30d6\u30e9\u30f3\u30c9\uff01 \u306e\u5275\u9020\u3092\u30d3\u30b8\u30e5\u30a2\u30eb-\u30a2\u30a4\u30c7\u30f3\u30c6\u30a3\u30c6\u30a3\u306e\u30d6\u30e9\u30f3\u30c9\u306e\u62c5\u308f\u308c\u3066\u3044\u307e\u3059\u304c\u3001\u305d\u308c\u306b\u3064\u3044\u3066\u306f\u3001\u30d3\u30b8\u30e5\u30a2\u30eb-\u30a2\u30a4\u30c7\u30f3\u30c6\u30a3\u30c6\u30a3\u306e\u30d6\u30e9\u30f3\u30c9\u3067\u3059\u3002 \u3063\u3066\u3044\u308b\u306e\u3092\u3054\u5b58\u77e5\u306e\u767a\u8868\u3067\u3042\u3063\u305f\u3088\u3046\u306b\u601d\u304850%\u306e\u5897\u52a0\u7387\u306b\u9589\u3058\u308b\u3002 \u95a2","canonical_url":"https:\/\/platinumagencias.com\/ja\/criacao-de-identidade-visual-de-marca\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/platinumagencias.com\/ja\/criacao-de-identidade-visual-de-marca\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/platinumagencias.com\/ja#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/platinumagencias.com\/ja","nextItem":{"@type":"ListItem","@id":"https:\/\/platinumagencias.com\/ja\/criacao-de-identidade-visual-de-marca\/#listItem","name":"Cria\u00e7\u00e3o de Identidade Visual de Marca"}},{"@type":"ListItem","@id":"https:\/\/platinumagencias.com\/ja\/criacao-de-identidade-visual-de-marca\/#listItem","position":2,"name":"Cria\u00e7\u00e3o de Identidade Visual de Marca","previousItem":{"@type":"ListItem","@id":"https:\/\/platinumagencias.com\/ja#listItem","name":"In\u00edcio"}}]},{"@type":"Organization","@id":"https:\/\/platinumagencias.com\/ja\/#organization","name":"Ag\u00eancia Platinum","description":"Ag\u00eancia de Marketing Digital","url":"https:\/\/platinumagencias.com\/ja\/","logo":{"@type":"ImageObject","url":"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/cropped-Agencia-Platinum.png","@id":"https:\/\/platinumagencias.com\/ja\/criacao-de-identidade-visual-de-marca\/#organizationLogo"},"image":{"@id":"https:\/\/platinumagencias.com\/ja\/criacao-de-identidade-visual-de-marca\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/platinumagencias.com\/ja\/criacao-de-identidade-visual-de-marca\/#webpage","url":"https:\/\/platinumagencias.com\/ja\/criacao-de-identidade-visual-de-marca\/","name":"Cria\u00e7\u00e3o de Identidade Visual de Marca \u2013 Ag\u00eancia Platinum","description":"Cria\u00e7\u00e3o de Identidade Visual da Marca Conhe\u00e7a um pouco mais dos nosso pacote de cria\u00e7\u00e3o de identidade visual de marca! Cria\u00e7\u00e3o de Identidade Visual da Marca Nos encarregamos de criar toda a identidade visual da sua marca. Voc\u00ea sabia que uma apresenta\u00e7\u00e3o bem elaborada aumenta em 50% as chances de fechar um neg\u00f3cio? Conte com","inLanguage":"ja","isPartOf":{"@id":"https:\/\/platinumagencias.com\/ja\/#website"},"breadcrumb":{"@id":"https:\/\/platinumagencias.com\/ja\/criacao-de-identidade-visual-de-marca\/#breadcrumblist"},"datePublished":"2024-03-11T14:01:56-03:00","dateModified":"2024-03-12T11:50:50-03:00"},{"@type":"WebSite","@id":"https:\/\/platinumagencias.com\/ja\/#website","url":"https:\/\/platinumagencias.com\/ja\/","name":"Ag\u00eancia Platinum","description":"Ag\u00eancia de Marketing Digital","inLanguage":"ja","publisher":{"@id":"https:\/\/platinumagencias.com\/ja\/#organization"}}]},"og:locale":"ja_JP","og:site_name":"Ag\u00eancia Platinum \u2013 Ag\u00eancia de Marketing Digital","og:type":"article","og:title":"Cria\u00e7\u00e3o de Identidade Visual de Marca \u2013 Ag\u00eancia Platinum","og:description":"Cria\u00e7\u00e3o de Identidade Visual da Marca Conhe\u00e7a um pouco mais dos nosso pacote de cria\u00e7\u00e3o de identidade visual de marca! Cria\u00e7\u00e3o de Identidade Visual da Marca Nos encarregamos de criar toda a identidade visual da sua marca. Voc\u00ea sabia que uma apresenta\u00e7\u00e3o bem elaborada aumenta em 50% as chances de fechar um neg\u00f3cio? Conte com","og:url":"https:\/\/platinumagencias.com\/ja\/criacao-de-identidade-visual-de-marca\/","og:image":"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/cropped-Design-sem-nome-2022-10-11T100526.548.png","og:image:secure_url":"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/cropped-Design-sem-nome-2022-10-11T100526.548.png","og:image:width":500,"og:image:height":325,"article:published_time":"2024-03-11T17:01:56+00:00","article:modified_time":"2024-03-12T14:50:50+00:00","twitter:card":"summary_large_image","twitter:title":"Cria\u00e7\u00e3o de Identidade Visual de Marca \u2013 Ag\u00eancia Platinum","twitter:description":"Cria\u00e7\u00e3o de Identidade Visual da Marca Conhe\u00e7a um pouco mais dos nosso pacote de cria\u00e7\u00e3o de identidade visual de marca! Cria\u00e7\u00e3o de Identidade Visual da Marca Nos encarregamos de criar toda a identidade visual da sua marca. Voc\u00ea sabia que uma apresenta\u00e7\u00e3o bem elaborada aumenta em 50% as chances de fechar um neg\u00f3cio? Conte com","twitter:image":"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/cropped-Design-sem-nome-2022-10-11T100526.548.png"},"aioseo_meta_data":{"post_id":"2506","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"created":"2024-03-11 17:01:57","updated":"2026-07-21 18:15:14","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/platinumagencias.com\/ja\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCria\u00e7\u00e3o de Identidade Visual de Marca\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/platinumagencias.com\/ja"},{"label":"Cria\u00e7\u00e3o de Identidade Visual de Marca","link":"https:\/\/platinumagencias.com\/ja\/criacao-de-identidade-visual-de-marca\/"}],"_links":{"self":[{"href":"https:\/\/platinumagencias.com\/ja\/wp-json\/wp\/v2\/pages\/2506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/platinumagencias.com\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/platinumagencias.com\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/platinumagencias.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/platinumagencias.com\/ja\/wp-json\/wp\/v2\/comments?post=2506"}],"version-history":[{"count":7,"href":"https:\/\/platinumagencias.com\/ja\/wp-json\/wp\/v2\/pages\/2506\/revisions"}],"predecessor-version":[{"id":2578,"href":"https:\/\/platinumagencias.com\/ja\/wp-json\/wp\/v2\/pages\/2506\/revisions\/2578"}],"wp:attachment":[{"href":"https:\/\/platinumagencias.com\/ja\/wp-json\/wp\/v2\/media?parent=2506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}