{"id":1111,"date":"2021-02-03T04:00:01","date_gmt":"2021-02-03T04:00:01","guid":{"rendered":"https:\/\/platinumagencias.com\/home\/"},"modified":"2026-03-21T11:44:10","modified_gmt":"2026-03-21T14:44:10","slug":"home","status":"publish","type":"page","link":"https:\/\/platinumagencias.com\/pa\/","title":{"rendered":"\u0a18\u0a30"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1111\" class=\"elementor elementor-1111\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-748a8c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"748a8c9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_privacy_mode&quot;:&quot;yes&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-402e0ce\" data-id=\"402e0ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1a1cdc elementor-widget elementor-widget-heading\" data-id=\"d1a1cdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Ag\u00eancia Platinum<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98780e1 elementor-widget elementor-widget-heading\" data-id=\"98780e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Todos os servi\u00e7os de Marketing Digital em um s\u00f3 lugar<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b62322 elementor-widget elementor-widget-text-editor\" data-id=\"5b62322\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chegou a hora de transformar a sua empresa! O melhor custo benef\u00edcio do mercado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e47f624 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e47f624\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/api.whatsapp.com\/send?phone=5511994952660&#038;text=Ol%C3%A1%20tudo%20bem%3F%20Gostaria%20de%20conhecer%20um%20pouco%20mais%20dos%20servi%C3%A7os%20de%20voc%C3%AAs!\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Fazer Or\u00e7amento<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bb2be4 elementor-widget elementor-widget-heading\" data-id=\"9bb2be4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Alguns dos nossos parceiros<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b2f90b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2f90b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-14 elementor-inner-column elementor-element elementor-element-92870f7\" data-id=\"92870f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f5ccef elementor-widget elementor-widget-image\" data-id=\"5f5ccef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.hostg.xyz\/aff_c?offer_id=6&#038;aff_id=104900\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"100\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/Design-sem-nome-2022-10-17T150704.727.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-1193\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/Design-sem-nome-2022-10-17T150704.727.png 200w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/Design-sem-nome-2022-10-17T150704.727-150x75.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-14 elementor-inner-column elementor-element elementor-element-f230567\" data-id=\"f230567\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-220d6d1 elementor-widget elementor-widget-image\" data-id=\"220d6d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/instagram.com\/hcamargo_cenografia\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"100\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/Design-sem-nome-2022-10-17T150824.576.png\" class=\"attachment-full size-full wp-image-1194\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/Design-sem-nome-2022-10-17T150824.576.png 200w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/Design-sem-nome-2022-10-17T150824.576-150x75.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-14 elementor-inner-column elementor-element elementor-element-515c310\" data-id=\"515c310\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fa7cad elementor-widget elementor-widget-image\" data-id=\"1fa7cad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/grupoclean4.com.br\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"100\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/Design-sem-nome-2022-10-17T150942.499.png\" class=\"attachment-full size-full wp-image-1195\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/Design-sem-nome-2022-10-17T150942.499.png 200w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/Design-sem-nome-2022-10-17T150942.499-150x75.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-14 elementor-inner-column elementor-element elementor-element-12945f9\" data-id=\"12945f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-350eebe elementor-widget elementor-widget-image\" data-id=\"350eebe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ecosmartlavanderia.com.br\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"500\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/12\/Logo-EcoSmart-V2.png\" class=\"attachment-full size-full wp-image-2998\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/12\/Logo-EcoSmart-V2.png 1000w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/12\/Logo-EcoSmart-V2-300x150.png 300w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/12\/Logo-EcoSmart-V2-768x384.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-14 elementor-inner-column elementor-element elementor-element-3835dd6\" data-id=\"3835dd6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b0da4a elementor-widget elementor-widget-image\" data-id=\"7b0da4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.tigre.com.br\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"500\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/12\/Logo-Tigre-Transparente.png\" class=\"attachment-full size-full wp-image-2992\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/12\/Logo-Tigre-Transparente.png 1000w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/12\/Logo-Tigre-Transparente-300x150.png 300w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/12\/Logo-Tigre-Transparente-768x384.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-14 elementor-inner-column elementor-element elementor-element-108cc0b\" data-id=\"108cc0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8049ba elementor-widget elementor-widget-image\" data-id=\"d8049ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/emilio.com.br\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"100\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/Design-sem-nome-2022-10-17T151253.564.png\" class=\"attachment-full size-full wp-image-1197\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/Design-sem-nome-2022-10-17T151253.564.png 200w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/Design-sem-nome-2022-10-17T151253.564-150x75.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-14 elementor-inner-column elementor-element elementor-element-f455be7\" data-id=\"f455be7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c61c63d elementor-widget elementor-widget-image\" data-id=\"c61c63d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/maiagraf.com.br\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"384\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2025\/01\/Logo-Maiagraf-3-768x384.png\" class=\"attachment-medium_large size-medium_large wp-image-3065\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2025\/01\/Logo-Maiagraf-3-768x384.png 768w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2025\/01\/Logo-Maiagraf-3-300x150.png 300w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2025\/01\/Logo-Maiagraf-3.png 1000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b1cd4d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b1cd4d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2789f2e\" data-id=\"2789f2e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee811fe elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ee811fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4254585 elementor-widget elementor-widget-heading\" data-id=\"4254585\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Principais Servi\u00e7os<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41a731e elementor-widget elementor-widget-text-editor\" data-id=\"41a731e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entendemos a realidade de cada empresa e possu\u00edmos pacotes ajustados que cabem no seu or\u00e7amento!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc61a95 elementor-widget elementor-widget-text-editor\" data-id=\"fc61a95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tVamos transformar a sua empresa naquilo que ela precisa ser: Focada nos meios digitais, identidade <a href=\"https:\/\/bayfieldvaltex.org\">https:\/\/bayfieldvaltex.org<\/a> Bayfield Valtex visual atrativa e gerando leads qualificados.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73414b4 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"73414b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/platinumagencias.com\/servicos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Saiba Mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-292c012 elementor-widget elementor-widget-image\" data-id=\"292c012\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"960\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/11\/Design-sem-nome-2022-11-28T095428.624.png\" class=\"attachment-large size-large wp-image-1315\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/11\/Design-sem-nome-2022-11-28T095428.624.png 640w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/11\/Design-sem-nome-2022-11-28T095428.624-200x300.png 200w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/11\/Design-sem-nome-2022-11-28T095428.624-150x225.png 150w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4065ff6\" data-id=\"4065ff6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e8d480f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8d480f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c573346\" data-id=\"c573346\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1b97fd elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f1b97fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1a74be0\" data-id=\"1a74be0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00a27f5 elementor-widget elementor-widget-heading\" data-id=\"00a27f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Gerenciamento de M\u00eddias Sociais<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00a5d47 elementor-widget elementor-widget-text-editor\" data-id=\"00a5d47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Como est\u00e1 o posicionamento da sua marca nas redes sociais? O servi\u00e7o de gerenciamento de m\u00eddias sociais da Platinum \u00e9 o mais completo do mercado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fa3747 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"3fa3747\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/api.whatsapp.com\/send?phone=5511994952660&#038;text=Ol%C3%A1%20tudo%20bem%3F%20Gostaria%20de%20conhecer%20um%20pouco%20mais%20dos%20servi%C3%A7os%20de%20voc%C3%AAs!\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Fazer or\u00e7amento<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-93d1475 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"93d1475\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a2624c\" data-id=\"7a2624c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7034f9c elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7034f9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fab fa-connectdevelop\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d42f871\" data-id=\"d42f871\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d2eddf elementor-widget elementor-widget-heading\" data-id=\"0d2eddf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Desenvolvimento de Site <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c9a58a elementor-widget elementor-widget-text-editor\" data-id=\"8c9a58a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Preparado para fazer o site da sua empresa? Com nossa cria\u00e7\u00e3o de site sua empresa vai al\u00e9m da concorr\u00eancia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98bdc7c elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"98bdc7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/api.whatsapp.com\/send?phone=5511994952660&#038;text=Ol%C3%A1%20tudo%20bem%3F%20Gostaria%20de%20conhecer%20um%20pouco%20mais%20dos%20servi%C3%A7os%20de%20voc%C3%AAs!\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Fazer or\u00e7amento<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-24c431a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24c431a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b97306b\" data-id=\"b97306b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1416e39 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1416e39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bullhorn\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e352e48\" data-id=\"e352e48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d141d25 elementor-widget elementor-widget-heading\" data-id=\"d141d25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Tr\u00e1fego Pago (An\u00fancios)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b758570 elementor-widget elementor-widget-text-editor\" data-id=\"b758570\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chegou o momento da sua empresa alcan\u00e7ar at\u00e9 1000x mais seu p\u00fablico-alvo com os an\u00fancios criados pela Platinum! (Google Ads, Face Ads e muito mais!)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-414b703 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"414b703\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/api.whatsapp.com\/send?phone=5511994952660&#038;text=Ol%C3%A1%20tudo%20bem%3F%20Gostaria%20de%20conhecer%20um%20pouco%20mais%20dos%20servi%C3%A7os%20de%20voc%C3%AAs!\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Fazer or\u00e7amento<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-87df2c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87df2c7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7d6db2a\" data-id=\"7d6db2a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37fb558 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"37fb558\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-toolbox\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-66fab40\" data-id=\"66fab40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9b78d4 elementor-widget elementor-widget-heading\" data-id=\"d9b78d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Manuten\u00e7\u00e3o de Site<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30ab131 elementor-widget elementor-widget-text-editor\" data-id=\"30ab131\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cria\u00e7\u00e3o de blog para melhorar o SEO do seu site, otimiza\u00e7\u00e3o da est\u00e9tica, cadastro de produtos e melhoria de ecommerce.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55976d5 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"55976d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/api.whatsapp.com\/send?phone=5511994952660&#038;text=Ol%C3%A1%20tudo%20bem%3F%20Gostaria%20de%20conhecer%20um%20pouco%20mais%20dos%20servi%C3%A7os%20de%20voc%C3%AAs!\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Fazer or\u00e7amento<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d0d9b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d0d9b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8a8823b\" data-id=\"8a8823b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51e84f8 elementor-widget elementor-widget-counter\" data-id=\"51e84f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Sites Criados<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"70\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d2ea780\" data-id=\"d2ea780\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0c701e elementor-widget elementor-widget-counter\" data-id=\"c0c701e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Clientes satisfeitos\u200b<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"120\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e717c80\" data-id=\"e717c80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa04de9 elementor-widget elementor-widget-counter\" data-id=\"fa04de9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Contas Ativas de Social Media\u200b<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"150\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-0722370\" data-id=\"0722370\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38570f0 elementor-widget elementor-widget-counter\" data-id=\"38570f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Campanhas Criadas\u200b<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"240\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c08023 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c08023\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-142d8e6\" data-id=\"142d8e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7273b5 elementor-widget elementor-widget-heading\" data-id=\"e7273b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Depoimentos sobre a Ag\u00eancia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0ba2797 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ba2797\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f05790c\" data-id=\"f05790c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5578a90 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5578a90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-quote-left\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f00192 elementor-widget elementor-widget-testimonial\" data-id=\"5f00192\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">RECOMENDO O TRABALHO DA PLATINUM! EXCELENTES PROFISSIONAIS COM UMA EQUIPE CAPACITADA! J\u00c1 FIZEMOS V\u00c1RIOS PROJETOS E OS RESULTADOS SEMPRE FORAM DE ALTO N\u00cdVEL E COM PLENA SATISFA\u00c7\u00c3O DOS CLIENTES!<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"50\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/Design-sem-nome-2022-10-13T151609.055.png\" class=\"attachment-full size-full wp-image-1150\" alt=\"\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Renato piza <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">Coach e Consultor<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-07169f7\" data-id=\"07169f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bd76a3 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3bd76a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-quote-left\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fa94e6 elementor-widget elementor-widget-testimonial\" data-id=\"0fa94e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">Trabalhar com a Platinum \u00e9 uma grande satisfa\u00e7\u00e3o, pois efetuam os servi\u00e7os com compromisso, pontualidade, nos ajudam com id\u00e9ias e solu\u00e7\u00f5es.<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"632\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/11\/56811586_1084464995087892_6977780078704852992_n.jpg\" class=\"attachment-full size-full wp-image-1362\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/11\/56811586_1084464995087892_6977780078704852992_n.jpg 632w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/11\/56811586_1084464995087892_6977780078704852992_n-300x300.jpg 300w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/11\/56811586_1084464995087892_6977780078704852992_n-150x150.jpg 150w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/11\/56811586_1084464995087892_6977780078704852992_n-96x96.jpg 96w\" sizes=\"(max-width: 632px) 100vw, 632px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Sylvia Hacker<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">Ceo &amp; Founder EJC<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4773561 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4773561\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6c07e4b\" data-id=\"6c07e4b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9d85b0 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a9d85b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-quote-left\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8093368 elementor-widget elementor-widget-testimonial\" data-id=\"8093368\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">Contratamos a Platinum Ag\u00eancia para criar o site da Supera Consulting: o trabalho com Rodrigo foi muito profissional, colaborativo e alcan\u00e7amos um resultado acima ao inicial planejado. Um investimento bem feito num site bonito e  funcional<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"310\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/11\/sergio-lima-2_20210917105946HKZ7A4JrAh.jpg\" class=\"attachment-full size-full wp-image-1375\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/11\/sergio-lima-2_20210917105946HKZ7A4JrAh.jpg 200w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/11\/sergio-lima-2_20210917105946HKZ7A4JrAh-194x300.jpg 194w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/11\/sergio-lima-2_20210917105946HKZ7A4JrAh-150x233.jpg 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Sergio lima<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">CEO &amp; Founder Neovalor Consulting<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-20f1bdd\" data-id=\"20f1bdd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32bc532 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"32bc532\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-quote-left\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3797484 elementor-widget elementor-widget-testimonial\" data-id=\"3797484\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">A Platinum \u00e9 uma ag\u00eancia extremamente comprometida em entregar o melhor servi\u00e7o para n\u00f3s, sempre com um trabalho impec\u00e1vel tanto na quest\u00e3o de qualidade quanto na quest\u00e3o dos prazos, fazendo com que nossa empresa potencialize os lucros.<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/12\/cara-loiro-com-oculos-sentado-na_17863438_detail.jpg\" class=\"attachment-full size-full wp-image-1429\" alt=\"\" srcset=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/12\/cara-loiro-com-oculos-sentado-na_17863438_detail.jpg 600w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/12\/cara-loiro-com-oculos-sentado-na_17863438_detail-300x200.jpg 300w, https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/12\/cara-loiro-com-oculos-sentado-na_17863438_detail-150x100.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">David Hasbani<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">CEO Emilio Atacado<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67bbdfb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67bbdfb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce59f57\" data-id=\"ce59f57\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83ce887 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"83ce887\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c759ac elementor-widget elementor-widget-heading\" data-id=\"2c759ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Especialistas em Marketing Digital<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6e6fab elementor-widget elementor-widget-text-editor\" data-id=\"f6e6fab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A Platinum est\u00e1 inserida no mercado com o conceito: \u00d3timos profissionais por um pre\u00e7o acess\u00edvel. 100% de satisfa\u00e7\u00e3o de nossos clientes<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-229f2df elementor-align-center elementor-widget elementor-widget-button\" data-id=\"229f2df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/api.whatsapp.com\/send?phone=5511994952660&#038;text=Ol%C3%A1%20tudo%20bem%3F%20Gostaria%20de%20conhecer%20um%20pouco%20mais%20dos%20servi%C3%A7os%20de%20voc%C3%AAs!\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Fazer or\u00e7amento<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4de2dcd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4de2dcd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-265ebb2\" data-id=\"265ebb2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ca0386 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3ca0386\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fa5789 elementor-widget elementor-widget-heading\" data-id=\"4fa5789\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Portal de not\u00edcias Platinum<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9b12d3 elementor-widget elementor-widget-text-editor\" data-id=\"e9b12d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Confira as novidades do mercado em nosso portal de not\u00edcias para estar sempre atualizado e a frente dos seus concorrentes<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-065b31f elementor-align-left elementor-widget elementor-widget-button\" data-id=\"065b31f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/platinumagencias.com\/portaldenoticias\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver todas as mat\u00e9rias<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f924c4 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"9f924c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5921 post type-post status-publish format-standard hentry\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/platinumagencias.com\/pa\/jogar-poker-online-a-dinheiro\/\" >\n\t\t\t\tJogos de alto risco: a triste realidade de jogar poker online a dinheiro\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t13\/04\/2026\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\t\u0a15\u0a4b\u0a08 \u0a1f\u0a3f\u0a71\u0a2a\u0a23\u0a40 \u0a28\u0a39\u0a40\u0a02\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/platinumagencias.com\/pa\/jogar-poker-online-a-dinheiro\/\" aria-label=\"Read more about Jogos de alto risco: a triste realidade de jogar poker online a dinheiro\" tabindex=\"-1\" >\n\t\t\tLeia mais&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5920 post type-post status-publish format-standard hentry\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/platinumagencias.com\/pa\/melhores-casino-estrangeiros\/\" >\n\t\t\t\tOs \u201cmelhores casino estrangeiros\u201d s\u00e3o apenas mais uma ilus\u00e3o de marketing\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t13\/04\/2026\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\t\u0a15\u0a4b\u0a08 \u0a1f\u0a3f\u0a71\u0a2a\u0a23\u0a40 \u0a28\u0a39\u0a40\u0a02\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/platinumagencias.com\/pa\/melhores-casino-estrangeiros\/\" aria-label=\"Read more about Os \u201cmelhores casino estrangeiros\u201d s\u00e3o apenas mais uma ilus\u00e3o de marketing\" tabindex=\"-1\" >\n\t\t\tLeia mais&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5919 post type-post status-publish format-standard hentry\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/platinumagencias.com\/pa\/jogos-de-casino-gr%C3%A1tis-slot-machines\/\" >\n\t\t\t\tJogos de casino gr\u00e1tis slot machines: a ilus\u00e3o que ningu\u00e9m paga\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t13\/04\/2026\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\t\u0a15\u0a4b\u0a08 \u0a1f\u0a3f\u0a71\u0a2a\u0a23\u0a40 \u0a28\u0a39\u0a40\u0a02\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/platinumagencias.com\/pa\/jogos-de-casino-gr%C3%A1tis-slot-machines\/\" aria-label=\"Read more about Jogos de casino gr\u00e1tis slot machines: a ilus\u00e3o que ningu\u00e9m paga\" tabindex=\"-1\" >\n\t\t\tLeia mais&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5918 post type-post status-publish format-standard hentry\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/platinumagencias.com\/pa\/casino-sem-licen%C3%A7a-portugal\/\" >\n\t\t\t\tCasino sem licen\u00e7a Portugal: o caos oculto por tr\u00e1s das promessas de \u201cgift\u201d\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t13\/04\/2026\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\t\u0a15\u0a4b\u0a08 \u0a1f\u0a3f\u0a71\u0a2a\u0a23\u0a40 \u0a28\u0a39\u0a40\u0a02\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/platinumagencias.com\/pa\/casino-sem-licen%C3%A7a-portugal\/\" aria-label=\"Read more about Casino sem licen\u00e7a Portugal: o caos oculto por tr\u00e1s das promessas de \u201cgift\u201d\" tabindex=\"-1\" >\n\t\t\tLeia mais&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5917 post type-post status-publish format-standard hentry\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/platinumagencias.com\/pa\/bettilt-casino-c%C3%B3digo-b%C3%B3nus-exclusivo-sem-dep%C3%B3sito\/\" >\n\t\t\t\tBettilt casino c\u00f3digo b\u00f3nus exclusivo sem dep\u00f3sito: a jogada fria que nem o inverno de Lisboa\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t13\/04\/2026\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\t\u0a15\u0a4b\u0a08 \u0a1f\u0a3f\u0a71\u0a2a\u0a23\u0a40 \u0a28\u0a39\u0a40\u0a02\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/platinumagencias.com\/pa\/bettilt-casino-c%C3%B3digo-b%C3%B3nus-exclusivo-sem-dep%C3%B3sito\/\" aria-label=\"Read more about Bettilt casino c\u00f3digo b\u00f3nus exclusivo sem dep\u00f3sito: a jogada fria que nem o inverno de Lisboa\" tabindex=\"-1\" >\n\t\t\tLeia mais&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5916 post type-post status-publish format-standard hentry\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/platinumagencias.com\/pa\/paripesa-casino-b%C3%B3nus-de-registo-sem-dep%C3%B3sito-2026\/\" >\n\t\t\t\tParipesa casino b\u00f3nus de registo sem dep\u00f3sito 2026: O que ningu\u00e9m lhe conta sobre a ilus\u00e3o de \u201cgratuidade\u201d\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t13\/04\/2026\t\t<\/span>\n\t\t\t\t<span class=\"elementor-post-avatar\">\n\t\t\t\u0a15\u0a4b\u0a08 \u0a1f\u0a3f\u0a71\u0a2a\u0a23\u0a40 \u0a28\u0a39\u0a40\u0a02\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/platinumagencias.com\/pa\/paripesa-casino-b%C3%B3nus-de-registo-sem-dep%C3%B3sito-2026\/\" aria-label=\"Read more about Paripesa casino b\u00f3nus de registo sem dep\u00f3sito 2026: O que ningu\u00e9m lhe conta sobre a ilus\u00e3o de \u201cgratuidade\u201d\" tabindex=\"-1\" >\n\t\t\tLeia mais&gt;\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af2566e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af2566e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4968ccc\" data-id=\"4968ccc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-144b65d elementor-widget elementor-widget-heading\" data-id=\"144b65d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Entre em contato conosco<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1937000 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"1937000\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"1111\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"1937000\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Home \u2013 Ag\u00eancia Platinum\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"1111\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-number elementor-field-group elementor-column elementor-field-group-field_6773b09 elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_6773b09\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTelefone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t<input type=\"number\" name=\"form_fields[field_6773b09]\" id=\"form-field-field_6773b09\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Telefone\" required=\"required\" min=\"6\" max=\"\" >\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMensagem\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Mensagem\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_571492c elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_571492c]\" id=\"form-field-field_571492c\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\">\n\t\t\t\t<label for=\"form-field-field_571492c\">Confirmo que as informa\u00e7\u00f5es acima s\u00e3o verdadeiras<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e425ab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5e425ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-54ca29c\" data-id=\"54ca29c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85c165c elementor-widget elementor-widget-menu-anchor\" data-id=\"85c165c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"parceiros\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ag\u00eancia<\/p>","protected":false},"author":1,"featured_media":2304,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1111","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ag\u00eancia Platinum Todos os servi\u00e7os de Marketing Digital em um s\u00f3 lugar Chegou a hora de transformar a sua empresa! O melhor custo benef\u00edcio do mercado. Fazer Or\u00e7amento Alguns dos nossos parceiros Principais Servi\u00e7os Entendemos a realidade de cada empresa e possu\u00edmos pacotes ajustados que cabem no seu or\u00e7amento! Vamos transformar a sua empresa naquilo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/platinumagencias.com\/pa\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pa_IN\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ag\u00eancia Platinum \u2013 Ag\u00eancia de Marketing Digital\" \/>\n\t\t<meta property=\"og:type\" content=\"website\" \/>\n\t\t<meta property=\"og:title\" content=\"Home \u2013 Ag\u00eancia Platinum\" \/>\n\t\t<meta property=\"og:description\" content=\"Ag\u00eancia Platinum Todos os servi\u00e7os de Marketing Digital em um s\u00f3 lugar Chegou a hora de transformar a sua empresa! O melhor custo benef\u00edcio do mercado. Fazer Or\u00e7amento Alguns dos nossos parceiros Principais Servi\u00e7os Entendemos a realidade de cada empresa e possu\u00edmos pacotes ajustados que cabem no seu or\u00e7amento! Vamos transformar a sua empresa naquilo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/platinumagencias.com\/pa\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/cropped-Design-sem-nome-2022-10-11T100526.548.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/cropped-Design-sem-nome-2022-10-11T100526.548.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Home \u2013 Ag\u00eancia Platinum\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ag\u00eancia Platinum Todos os servi\u00e7os de Marketing Digital em um s\u00f3 lugar Chegou a hora de transformar a sua empresa! O melhor custo benef\u00edcio do mercado. Fazer Or\u00e7amento Alguns dos nossos parceiros Principais Servi\u00e7os Entendemos a realidade de cada empresa e possu\u00edmos pacotes ajustados que cabem no seu or\u00e7amento! Vamos transformar a sua empresa naquilo\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/cropped-Design-sem-nome-2022-10-11T100526.548.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa#listItem\",\"position\":1,\"name\":\"In\\u00edcio\",\"item\":\"https:\\\/\\\/platinumagencias.com\\\/pa\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/#listItem\",\"position\":2,\"name\":\"Home\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa#listItem\",\"name\":\"In\\u00edcio\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/#organization\",\"name\":\"Ag\\u00eancia Platinum\",\"description\":\"Ag\\u00eancia de Marketing Digital\",\"url\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/platinumagencias.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-Agencia-Platinum.png\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/daf561345d0565e9e941f2ed84ae8436d461cfa8b169fd8d92b254b996a35957?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/#webpage\",\"url\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/\",\"name\":\"Home \\u2013 Ag\\u00eancia Platinum\",\"description\":\"Ag\\u00eancia Platinum Todos os servi\\u00e7os de Marketing Digital em um s\\u00f3 lugar Chegou a hora de transformar a sua empresa! O melhor custo benef\\u00edcio do mercado. Fazer Or\\u00e7amento Alguns dos nossos parceiros Principais Servi\\u00e7os Entendemos a realidade de cada empresa e possu\\u00edmos pacotes ajustados que cabem no seu or\\u00e7amento! Vamos transformar a sua empresa naquilo\",\"inLanguage\":\"pa-IN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/#mainImage\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/#mainImage\"},\"datePublished\":\"2021-02-03T04:00:01-03:00\",\"dateModified\":\"2026-03-21T11:44:10-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/#website\",\"url\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/\",\"name\":\"Ag\\u00eancia Platinum\",\"description\":\"Ag\\u00eancia de Marketing Digital\",\"inLanguage\":\"pa-IN\",\"publisher\":{\"@id\":\"https:\\\/\\\/platinumagencias.com\\\/pa\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u0a18\u0a30 \u0a35\u0a3f\u0a71\u0a1a \u0a06\u0a2b\u0a3c\u0a3f\u0a38\u0a3c \u0a39\u0a48 Platinum","description":"Ag\u00eancia Platinum Todos os servi\u00e7os de Marketing Digital em um s\u00f3 lugar Chegou a hora de transformar a sua empresa! O melhor custo benef\u00edcio do mercado. Fazer Or\u00e7amento Alguns dos nossos parceiros Principais Servi\u00e7os Entendemos a realidade de cada empresa e possu\u00edmos pacotes ajustados que cabem no seu or\u00e7amento! Vamos transformar a sua empresa naquilo","canonical_url":"https:\/\/platinumagencias.com\/pa\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/platinumagencias.com\/pa\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/platinumagencias.com\/pa#listItem","position":1,"name":"In\u00edcio","item":"https:\/\/platinumagencias.com\/pa","nextItem":{"@type":"ListItem","@id":"https:\/\/platinumagencias.com\/pa\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/platinumagencias.com\/pa\/#listItem","position":2,"name":"Home","previousItem":{"@type":"ListItem","@id":"https:\/\/platinumagencias.com\/pa#listItem","name":"In\u00edcio"}}]},{"@type":"Organization","@id":"https:\/\/platinumagencias.com\/pa\/#organization","name":"Ag\u00eancia Platinum","description":"Ag\u00eancia de Marketing Digital","url":"https:\/\/platinumagencias.com\/pa\/","logo":{"@type":"ImageObject","url":"https:\/\/platinumagencias.com\/wp-content\/uploads\/2024\/03\/cropped-Agencia-Platinum.png","@id":"https:\/\/platinumagencias.com\/pa\/#organizationLogo"},"image":{"@id":"https:\/\/platinumagencias.com\/pa\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/platinumagencias.com\/pa\/author\/admin\/#author","url":"https:\/\/platinumagencias.com\/pa\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/platinumagencias.com\/pa\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/daf561345d0565e9e941f2ed84ae8436d461cfa8b169fd8d92b254b996a35957?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/platinumagencias.com\/pa\/#webpage","url":"https:\/\/platinumagencias.com\/pa\/","name":"Home \u2013 Ag\u00eancia Platinum","description":"Ag\u00eancia Platinum Todos os servi\u00e7os de Marketing Digital em um s\u00f3 lugar Chegou a hora de transformar a sua empresa! O melhor custo benef\u00edcio do mercado. Fazer Or\u00e7amento Alguns dos nossos parceiros Principais Servi\u00e7os Entendemos a realidade de cada empresa e possu\u00edmos pacotes ajustados que cabem no seu or\u00e7amento! Vamos transformar a sua empresa naquilo","inLanguage":"pa-IN","isPartOf":{"@id":"https:\/\/platinumagencias.com\/pa\/#website"},"breadcrumb":{"@id":"https:\/\/platinumagencias.com\/pa\/#breadcrumblist"},"author":{"@id":"https:\/\/platinumagencias.com\/pa\/author\/admin\/#author"},"creator":{"@id":"https:\/\/platinumagencias.com\/pa\/author\/admin\/#author"},"image":{"@type":"ImageObject","@id":"https:\/\/platinumagencias.com\/pa\/#mainImage"},"primaryImageOfPage":{"@id":"https:\/\/platinumagencias.com\/pa\/#mainImage"},"datePublished":"2021-02-03T04:00:01-03:00","dateModified":"2026-03-21T11:44:10-03:00"},{"@type":"WebSite","@id":"https:\/\/platinumagencias.com\/pa\/#website","url":"https:\/\/platinumagencias.com\/pa\/","name":"Ag\u00eancia Platinum","description":"Ag\u00eancia de Marketing Digital","inLanguage":"pa-IN","publisher":{"@id":"https:\/\/platinumagencias.com\/pa\/#organization"}}]},"og:locale":"pa_IN","og:site_name":"Ag\u00eancia Platinum \u2013 Ag\u00eancia de Marketing Digital","og:type":"website","og:title":"Home \u2013 Ag\u00eancia Platinum","og:description":"Ag\u00eancia Platinum Todos os servi\u00e7os de Marketing Digital em um s\u00f3 lugar Chegou a hora de transformar a sua empresa! O melhor custo benef\u00edcio do mercado. Fazer Or\u00e7amento Alguns dos nossos parceiros Principais Servi\u00e7os Entendemos a realidade de cada empresa e possu\u00edmos pacotes ajustados que cabem no seu or\u00e7amento! Vamos transformar a sua empresa naquilo","og:url":"https:\/\/platinumagencias.com\/pa\/","og:image":"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/cropped-Design-sem-nome-2022-10-11T100526.548.png","og:image:secure_url":"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/cropped-Design-sem-nome-2022-10-11T100526.548.png","og:image:width":500,"og:image:height":325,"twitter:card":"summary_large_image","twitter:title":"Home \u2013 Ag\u00eancia Platinum","twitter:description":"Ag\u00eancia Platinum Todos os servi\u00e7os de Marketing Digital em um s\u00f3 lugar Chegou a hora de transformar a sua empresa! O melhor custo benef\u00edcio do mercado. Fazer Or\u00e7amento Alguns dos nossos parceiros Principais Servi\u00e7os Entendemos a realidade de cada empresa e possu\u00edmos pacotes ajustados que cabem no seu or\u00e7amento! Vamos transformar a sua empresa naquilo","twitter:image":"https:\/\/platinumagencias.com\/wp-content\/uploads\/2022\/10\/cropped-Design-sem-nome-2022-10-11T100526.548.png"},"aioseo_meta_data":{"post_id":"1111","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"website","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"created":"2022-12-01 13:13:38","updated":"2026-07-21 18:13:13","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/platinumagencias.com\/pa\" title=\"In\u00edcio\">In\u00edcio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHome\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"In\u00edcio","link":"https:\/\/platinumagencias.com\/pa"},{"label":"Home","link":"https:\/\/platinumagencias.com\/pa\/"}],"_links":{"self":[{"href":"https:\/\/platinumagencias.com\/pa\/wp-json\/wp\/v2\/pages\/1111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/platinumagencias.com\/pa\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/platinumagencias.com\/pa\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/platinumagencias.com\/pa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/platinumagencias.com\/pa\/wp-json\/wp\/v2\/comments?post=1111"}],"version-history":[{"count":256,"href":"https:\/\/platinumagencias.com\/pa\/wp-json\/wp\/v2\/pages\/1111\/revisions"}],"predecessor-version":[{"id":3834,"href":"https:\/\/platinumagencias.com\/pa\/wp-json\/wp\/v2\/pages\/1111\/revisions\/3834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/platinumagencias.com\/pa\/wp-json\/wp\/v2\/media\/2304"}],"wp:attachment":[{"href":"https:\/\/platinumagencias.com\/pa\/wp-json\/wp\/v2\/media?parent=1111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}